{"id":30515,"date":"2022-08-31T07:05:37","date_gmt":"2022-08-31T07:05:37","guid":{"rendered":"https:\/\/easydmarc.com\/blog\/?p=30515"},"modified":"2025-08-07T08:47:20","modified_gmt":"2025-08-07T08:47:20","slug":"registros-a-frente-a-registros-aaaa","status":"publish","type":"post","link":"https:\/\/easydmarc.com\/blog\/es\/registros-a-frente-a-registros-aaaa\/","title":{"rendered":"Registros A frente a Registros AAAA"},"content":{"rendered":"<p><b>Los registros A y los registro AAAA<\/b><span style=\"font-weight: 400;\"> son dos tipos distintos de registros de hosting para DNS, que tiene la funci\u00f3n de resolver el nombre de un servicio hosting frente a una direcci\u00f3n IP.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aunque ambos registros son similares, estos poseen sus marcadas diferencias, la cuales resaltan a la vista si llevas a cabo una b\u00fasqueda de registros DNS para tu sitio web, la cual te mostrar\u00e1 una lista de registros DNS diversificados.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Comprender las diferencias entre los registros TXT, los registros PTR, los registros CNAME, los registros SOA, los registros MX, los registros NS, los registros y los registros AAAA es esencial si eres el administrador o propietario de un sitio web.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En este art\u00edculo, vamos a destacar algunas diferencias entre los <\/span><b>registros A frente a los registros AAAA<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h2><b>El registro A<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">\u00bfQu\u00e9 es un registro para el DNS? Podr\u00edamos decir que es uno de los tipos de registro m\u00e1s esenciales en cualquier infraestructura de correo electr\u00f3nico. Para el funcionamiento \u00f3ptimo de cualquier buz\u00f3n de mensajes corporativo se requiere un registro A para resolver un FQDN (nombre de dominio calificado) en una direcci\u00f3n IPv4.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por ejemplo, si <\/span><b>solicitas el registro A<\/b><span style=\"font-weight: 400;\"> de MyWebSite.com, el servidor enviar\u00e1 de vuelta la direcci\u00f3n IPv4 correspondiente, 192.168.10.1.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Un <\/span><b>registro A<\/b><span style=\"font-weight: 400;\"> generalmente se usa para hacer coincidir un sitio web con su identificador num\u00e9rico, pero tambi\u00e9n puede ser dirigido a la ra\u00edz de un dominio, ya que este registro DNS permite a los usuarios llegar a tu sitio web sin necesidad de memorizar e ingresar la direcci\u00f3n IP de forma manual.<\/span><\/p>\n<h2><b>El registro AAAA<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Tal como sucede con el registro A, <\/span><b>los registros DNS AAAA<\/b><span style=\"font-weight: 400;\"> se enfocan en conectar un nombre de dominio a una direcci\u00f3n IP, pero en lugar de se\u00f1alar una direcci\u00f3n IPv4, el <\/span><b>registro AAAA<\/b><span style=\"font-weight: 400;\"> es utilizado para las direcciones IPv6. IPv4 e IPv6 identifica un nodo o computador en la Internet.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sin embargo, las direcciones IPv6 son la versi\u00f3n renovada y m\u00e1s extensa del antiguo protocolo IPv4, por lo que si buscas alcanzar la direcci\u00f3n mywebsite.com usando un <\/span><b>registro AAAA<\/b><span style=\"font-weight: 400;\">, obtendr\u00e1s una cadena de d\u00edgitos hexadecimales, tal como 2011: 0dc8: 45b4: 0300:<\/span><\/p>\n<h2><b>Un registro A comparado con un registro AAAA<\/b><\/h2>\n<p><b>Los registros A y AAAA<\/b><span style=\"font-weight: 400;\"> o \u00abQuad A\u00bb son registros DNS esenciales para los sistemas nominales de dominio; la principal diferencia entre ambos es que un <\/span><b>registro A<\/b><span style=\"font-weight: 400;\"> resuelve el nombre de dominio en sus direcciones IPv4 correspondientes, mientras que un <\/span><b>registro AAAA<\/b><span style=\"font-weight: 400;\"> resuelve el nombre de dominio en direcciones IPv6 que est\u00e9n relacionadas a la b\u00fasqueda espec\u00edfica.<\/span><\/p>\n<h2><b>Resumen<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Puedes apreciar que hemos explicado la <\/span><b>diferencia m\u00e1s notable entre un registro AAAA y un registro A<\/b><span style=\"font-weight: 400;\">; ambos son usados para el mismo prop\u00f3sito dentro de los sistemas de nombres de dominio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ambos tipos de registros DNS resuelven la b\u00fasqueda y ubicaci\u00f3n del nombre de dominio de un sitio web ante la direcci\u00f3n ITSIP (la cual generalmente es dif\u00edcil de recordar). El primer tipo de registro se utiliza para las direcciones IPv4 y la segunda es necesaria para las direcciones IP IPv6.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los registros A y los registro AAAA son &#8230;<\/p>\n","protected":false},"author":58,"featured_media":32625,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[474,413],"tags":[],"class_list":["post-30515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conocimiento-base","category-registros-dns"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Registros A frente a Registros AAAA | EasyDMARC<\/title>\n<meta name=\"description\" content=\"Registros A vs AAAA: entiende c\u00f3mo funcionan, en qu\u00e9 se diferencian y por qu\u00e9 son esenciales para la configuraci\u00f3n y seguridad de tu sitio web.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/easydmarc.com\/blog\/es\/registros-a-frente-a-registros-aaaa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Registros A frente a Registros AAAA\" \/>\n<meta property=\"og:description\" content=\"Registros A vs AAAA: entiende c\u00f3mo funcionan, en qu\u00e9 se diferencian y por qu\u00e9 son esenciales para la configuraci\u00f3n y seguridad de tu sitio web.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/easydmarc.com\/blog\/es\/registros-a-frente-a-registros-aaaa\/\" \/>\n<meta property=\"og:site_name\" content=\"EasyDMARC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EasyDMARC\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-31T07:05:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-07T08:47:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/easydmarc.com\/blog\/wp-content\/uploads\/2022\/08\/A-Record-vs-AAAA-Record-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"911\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ruben Khachatryan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@easydmarc\" \/>\n<meta name=\"twitter:site\" content=\"@easydmarc\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ruben Khachatryan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/registros-a-frente-a-registros-aaaa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/registros-a-frente-a-registros-aaaa\\\/\"},\"author\":{\"name\":\"Ruben Khachatryan\",\"@id\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/#\\\/schema\\\/person\\\/9766f07d4ef9704ee4f6810b32788c1c\"},\"headline\":\"Registros A frente a Registros AAAA\",\"datePublished\":\"2022-08-31T07:05:37+00:00\",\"dateModified\":\"2025-08-07T08:47:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/registros-a-frente-a-registros-aaaa\\\/\"},\"wordCount\":537,\"publisher\":{\"@id\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/registros-a-frente-a-registros-aaaa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/A-Record-vs-AAAA-Record-1.jpg\",\"articleSection\":[\"Conocimiento Base\",\"Registros DNS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/registros-a-frente-a-registros-aaaa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/registros-a-frente-a-registros-aaaa\\\/\",\"url\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/registros-a-frente-a-registros-aaaa\\\/\",\"name\":\"Registros A frente a Registros AAAA | EasyDMARC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/registros-a-frente-a-registros-aaaa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/registros-a-frente-a-registros-aaaa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/A-Record-vs-AAAA-Record-1.jpg\",\"datePublished\":\"2022-08-31T07:05:37+00:00\",\"dateModified\":\"2025-08-07T08:47:20+00:00\",\"description\":\"Registros A vs AAAA: entiende c\u00f3mo funcionan, en qu\u00e9 se diferencian y por qu\u00e9 son esenciales para la configuraci\u00f3n y seguridad de tu sitio web.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/registros-a-frente-a-registros-aaaa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/registros-a-frente-a-registros-aaaa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/registros-a-frente-a-registros-aaaa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/A-Record-vs-AAAA-Record-1.jpg\",\"contentUrl\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/A-Record-vs-AAAA-Record-1.jpg\",\"width\":1440,\"height\":911,\"caption\":\"Avs and AAAA written on a blue background\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/registros-a-frente-a-registros-aaaa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/easydmarc.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conocimiento Base\",\"item\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/category\\\/conocimiento-base\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Registros DNS\",\"item\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/category\\\/conocimiento-base\\\/registros-dns\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Registros A frente a Registros AAAA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/\",\"name\":\"EasyDMARC\",\"description\":\"Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/easydmarc.com\\\/#organization\",\"name\":\"EasyDMARC\",\"url\":\"https:\\\/\\\/easydmarc.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/easydmarc.com\\\/img\\\/logo.png\"},\"image\":{\"@id\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EasyDMARC\\\/\",\"https:\\\/\\\/x.com\\\/easydmarc\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/easydmarc\\\/mycompany\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/#\\\/schema\\\/person\\\/9766f07d4ef9704ee4f6810b32788c1c\",\"name\":\"Ruben Khachatryan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f27eee0b7b7d4f7b6d1b4b7a485211ddd89e0e9205459180fc36e502b22ee12?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f27eee0b7b7d4f7b6d1b4b7a485211ddd89e0e9205459180fc36e502b22ee12?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f27eee0b7b7d4f7b6d1b4b7a485211ddd89e0e9205459180fc36e502b22ee12?s=96&r=g\",\"caption\":\"Ruben Khachatryan\"},\"url\":\"https:\\\/\\\/easydmarc.com\\\/blog\\\/es\\\/author\\\/ruben\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Registros A frente a Registros AAAA | EasyDMARC","description":"Registros A vs AAAA: entiende c\u00f3mo funcionan, en qu\u00e9 se diferencian y por qu\u00e9 son esenciales para la configuraci\u00f3n y seguridad de tu sitio web.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/easydmarc.com\/blog\/es\/registros-a-frente-a-registros-aaaa\/","og_locale":"es_ES","og_type":"article","og_title":"Registros A frente a Registros AAAA","og_description":"Registros A vs AAAA: entiende c\u00f3mo funcionan, en qu\u00e9 se diferencian y por qu\u00e9 son esenciales para la configuraci\u00f3n y seguridad de tu sitio web.","og_url":"https:\/\/easydmarc.com\/blog\/es\/registros-a-frente-a-registros-aaaa\/","og_site_name":"EasyDMARC","article_publisher":"https:\/\/www.facebook.com\/EasyDMARC\/","article_published_time":"2022-08-31T07:05:37+00:00","article_modified_time":"2025-08-07T08:47:20+00:00","og_image":[{"width":1440,"height":911,"url":"https:\/\/easydmarc.com\/blog\/wp-content\/uploads\/2022\/08\/A-Record-vs-AAAA-Record-1.jpg","type":"image\/jpeg"}],"author":"Ruben Khachatryan","twitter_card":"summary_large_image","twitter_creator":"@easydmarc","twitter_site":"@easydmarc","twitter_misc":{"Escrito por":"Ruben Khachatryan","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/easydmarc.com\/blog\/es\/registros-a-frente-a-registros-aaaa\/#article","isPartOf":{"@id":"https:\/\/easydmarc.com\/blog\/es\/registros-a-frente-a-registros-aaaa\/"},"author":{"name":"Ruben Khachatryan","@id":"https:\/\/easydmarc.com\/blog\/es\/#\/schema\/person\/9766f07d4ef9704ee4f6810b32788c1c"},"headline":"Registros A frente a Registros AAAA","datePublished":"2022-08-31T07:05:37+00:00","dateModified":"2025-08-07T08:47:20+00:00","mainEntityOfPage":{"@id":"https:\/\/easydmarc.com\/blog\/es\/registros-a-frente-a-registros-aaaa\/"},"wordCount":537,"publisher":{"@id":"https:\/\/easydmarc.com\/blog\/es\/#organization"},"image":{"@id":"https:\/\/easydmarc.com\/blog\/es\/registros-a-frente-a-registros-aaaa\/#primaryimage"},"thumbnailUrl":"https:\/\/easydmarc.com\/blog\/wp-content\/uploads\/2022\/08\/A-Record-vs-AAAA-Record-1.jpg","articleSection":["Conocimiento Base","Registros DNS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/easydmarc.com\/blog\/es\/registros-a-frente-a-registros-aaaa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/easydmarc.com\/blog\/es\/registros-a-frente-a-registros-aaaa\/","url":"https:\/\/easydmarc.com\/blog\/es\/registros-a-frente-a-registros-aaaa\/","name":"Registros A frente a Registros AAAA | EasyDMARC","isPartOf":{"@id":"https:\/\/easydmarc.com\/blog\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/easydmarc.com\/blog\/es\/registros-a-frente-a-registros-aaaa\/#primaryimage"},"image":{"@id":"https:\/\/easydmarc.com\/blog\/es\/registros-a-frente-a-registros-aaaa\/#primaryimage"},"thumbnailUrl":"https:\/\/easydmarc.com\/blog\/wp-content\/uploads\/2022\/08\/A-Record-vs-AAAA-Record-1.jpg","datePublished":"2022-08-31T07:05:37+00:00","dateModified":"2025-08-07T08:47:20+00:00","description":"Registros A vs AAAA: entiende c\u00f3mo funcionan, en qu\u00e9 se diferencian y por qu\u00e9 son esenciales para la configuraci\u00f3n y seguridad de tu sitio web.","breadcrumb":{"@id":"https:\/\/easydmarc.com\/blog\/es\/registros-a-frente-a-registros-aaaa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/easydmarc.com\/blog\/es\/registros-a-frente-a-registros-aaaa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/easydmarc.com\/blog\/es\/registros-a-frente-a-registros-aaaa\/#primaryimage","url":"https:\/\/easydmarc.com\/blog\/wp-content\/uploads\/2022\/08\/A-Record-vs-AAAA-Record-1.jpg","contentUrl":"https:\/\/easydmarc.com\/blog\/wp-content\/uploads\/2022\/08\/A-Record-vs-AAAA-Record-1.jpg","width":1440,"height":911,"caption":"Avs and AAAA written on a blue background"},{"@type":"BreadcrumbList","@id":"https:\/\/easydmarc.com\/blog\/es\/registros-a-frente-a-registros-aaaa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/easydmarc.com\/"},{"@type":"ListItem","position":2,"name":"Conocimiento Base","item":"https:\/\/easydmarc.com\/blog\/es\/category\/conocimiento-base\/"},{"@type":"ListItem","position":3,"name":"Registros DNS","item":"https:\/\/easydmarc.com\/blog\/es\/category\/conocimiento-base\/registros-dns\/"},{"@type":"ListItem","position":4,"name":"Registros A frente a Registros AAAA"}]},{"@type":"WebSite","@id":"https:\/\/easydmarc.com\/blog\/es\/#website","url":"https:\/\/easydmarc.com\/blog\/es\/","name":"EasyDMARC","description":"Blog","publisher":{"@id":"https:\/\/easydmarc.com\/blog\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/easydmarc.com\/blog\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/easydmarc.com\/#organization","name":"EasyDMARC","url":"https:\/\/easydmarc.com\/","logo":{"@type":"ImageObject","url":"https:\/\/easydmarc.com\/img\/logo.png"},"image":{"@id":"https:\/\/easydmarc.com\/blog\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EasyDMARC\/","https:\/\/x.com\/easydmarc","https:\/\/www.linkedin.com\/company\/easydmarc\/mycompany\/"]},{"@type":"Person","@id":"https:\/\/easydmarc.com\/blog\/es\/#\/schema\/person\/9766f07d4ef9704ee4f6810b32788c1c","name":"Ruben Khachatryan","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5f27eee0b7b7d4f7b6d1b4b7a485211ddd89e0e9205459180fc36e502b22ee12?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5f27eee0b7b7d4f7b6d1b4b7a485211ddd89e0e9205459180fc36e502b22ee12?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f27eee0b7b7d4f7b6d1b4b7a485211ddd89e0e9205459180fc36e502b22ee12?s=96&r=g","caption":"Ruben Khachatryan"},"url":"https:\/\/easydmarc.com\/blog\/es\/author\/ruben\/"}]}},"jetpack_featured_media_url":"https:\/\/easydmarc.com\/blog\/wp-content\/uploads\/2022\/08\/A-Record-vs-AAAA-Record-1.jpg","_links":{"self":[{"href":"https:\/\/easydmarc.com\/blog\/es\/wp-json\/wp\/v2\/posts\/30515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easydmarc.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/easydmarc.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/easydmarc.com\/blog\/es\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/easydmarc.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=30515"}],"version-history":[{"count":1,"href":"https:\/\/easydmarc.com\/blog\/es\/wp-json\/wp\/v2\/posts\/30515\/revisions"}],"predecessor-version":[{"id":50728,"href":"https:\/\/easydmarc.com\/blog\/es\/wp-json\/wp\/v2\/posts\/30515\/revisions\/50728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/easydmarc.com\/blog\/es\/wp-json\/wp\/v2\/media\/32625"}],"wp:attachment":[{"href":"https:\/\/easydmarc.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=30515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/easydmarc.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=30515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/easydmarc.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=30515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}